﻿{"id":2707,"date":"2024-05-27T15:00:41","date_gmt":"2024-05-27T13:00:41","guid":{"rendered":"https:\/\/ambparigi.esteri.it\/?p=2707"},"modified":"2024-05-31T16:14:51","modified_gmt":"2024-05-31T14:14:51","slug":"elezioni-europee-2024-certificati-e-seggi-elettorali","status":"publish","type":"post","link":"https:\/\/ambparigi.esteri.it\/it\/news\/dall_ambasciata\/2024\/05\/elezioni-europee-2024-certificati-e-seggi-elettorali\/","title":{"rendered":"Elezioni europee 2024 &#8211; Certificati e seggi elettorali"},"content":{"rendered":"<p>\u00c8 in corso la spedizione dei certificati elettorali da parte del Ministero dell\u2019Interno all\u2019indirizzo di residenza in Francia degli elettori iscritti all\u2019AIRE che non abbiano optato per il voto per i membri del Parlamento europeo spettanti alla Francia. Nel certificato sono specificati giorni, orari e luogo della votazione.<\/p>\n<p>Tale certificato \u00e8 spedito anche agli elettori italiani che si trovano temporaneamente in Francia per motivi di studio o lavoro, e ai loro familiari conviventi, che abbiano presentato apposita domanda entro il 21 marzo scorso.<\/p>\n<p>A partire dal 4 giugno, gli elettori che fino a quel momento non abbiano ricevuto il certificato elettorale, potranno fare richiesta di un duplicato all\u2019Ufficio consolare della circoscrizione di competenza.<\/p>\n<p>Gli elenchi delle sezioni elettorali, istituite dai Consolati Generali in Francia, dove si svolgeranno venerd\u00ec 7 giugno e sabato 8 giugno le operazioni di voto per l\u2019elezione dei membri del Parlamento europeo spettanti all\u2019Italia, sono consultabili sui siti istituzionali dei Consolati Generali indicati in questa pagina [link: <a href=\"https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/\">https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/<\/a>].<\/p>\n<p><u>N.B.: nel certificato elettorale \u00e8 indicata la sezione elettorale a cui l\u2019elettore \u00e8 assegnato<\/u>.<\/p>\n<p>Per ulteriori informazioni, consultare la <a href=\"https:\/\/ambparigi.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/informazioni-sulle-elezioni-europee-2024\/\">sezione dedicata<\/a> del nostro sito alle Elezioni europee 2024.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/NOx3yWkwKbs?si=JOTy4YYfxuIOrTlY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"\u00c8 in corso la spedizione dei certificati elettorali da parte del Ministero dell\u2019Interno all\u2019indirizzo di residenza in Francia degli elettori iscritti all\u2019AIRE che non abbiano optato per il voto per i membri del Parlamento europeo spettanti alla Francia. Nel certificato sono specificati giorni, orari e luogo della votazione. Tale certificato \u00e8 spedito anche agli elettori [&hellip;]","protected":false},"author":6,"featured_media":2709,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-2707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2707"}],"version-history":[{"count":5,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2707\/revisions"}],"predecessor-version":[{"id":2720,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/posts\/2707\/revisions\/2720"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/media\/2709"}],"wp:attachment":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2707"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=2707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}