﻿{"id":2355,"date":"2024-03-08T14:23:27","date_gmt":"2024-03-08T13:23:27","guid":{"rendered":"https:\/\/ambparigi.esteri.it\/?page_id=2355"},"modified":"2024-04-17T11:13:53","modified_gmt":"2024-04-17T09:13:53","slug":"elezione-dei-rappresentanti-al-parlamento-europeo-spettanti-allitalia","status":"publish","type":"page","link":"https:\/\/ambparigi.esteri.it\/it\/servizi-consolari-e-visti\/servizi-per-il-cittadino-italiano\/elezione-dei-rappresentanti-al-parlamento-europeo-spettanti-allitalia\/","title":{"rendered":"Elezione dei rappresentanti al Parlamento europeo spettanti all\u2019Italia &#8211; Informazioni generali"},"content":{"rendered":"<p>Ai sensi del Decreto-legge 24 giugno 1994, n. 408, possono votare presso i seggi istituti dagli <a href=\"https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/\">uffici consolari italiani<\/a> in Francia per l\u2019elezione dei rappresentanti al Parlamento europeo spettanti all\u2019Italia:<\/p>\n<p>\u2013 i cittadini italiani residenti in Francia e iscritti all\u2019AIRE;<br \/>\n\u2013 i cittadini italiani e i familiari con essi conviventi che si trovano temporaneamente in Francia per motivi di studio o di lavoro, presentando all\u2019<a href=\"https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/\">ufficio consolare competente<\/a> per il luogo di temporaneo domicilio una domanda indirizzata al Sindaco del Comune italiano nelle cui liste elettorali sono iscritti. La richiesta deve essere presentata entro il 21 marzo 2024.<\/p>\n<p>Il voto in Francia per i membri del PE spettanti all\u2019Italia si esercita presso i seggi istituiti dagli <a href=\"https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/\">uffici consolari<\/a>. L\u2019elettore riceve da parte del Ministero dell\u2019Interno italiano all\u2019indirizzo di residenza in Francia il certificato elettorale, con l\u2019indicazione del seggio presso il quale potr\u00e0 votare, nonch\u00e9 della data e dell\u2019orario di apertura per le votazioni.<\/p>\n<p>Qualora l\u2019elettore non riceva il certificato elettorale entro il 5\u00b0 giorno antecedente quello delle votazioni, potr\u00e0 contattare <a href=\"https:\/\/ambparigi.esteri.it\/it\/chi-siamo\/la-rete-consolare\/\">l\u2019ufficio consolare competente<\/a> per verificare la propria posizione elettorale e richiedere il certificato sostitutivo per l\u2019ammissione al voto.<\/p>\n<p>L\u2019elettore italiano residente in Francia, o ivi domiciliato temporaneamente per motivi di studio o lavoro (che abbia presentato domanda di voto in Francia nei termini previsti), se rientra in Italia, pu\u00f2 votare presso il proprio Comune di iscrizione elettorale: in tal caso deve farne esplicita richiesta, entro il giorno precedente quello della votazione, al Sindaco del suddetto Comune.<\/p>\n<p>L\u2019elettore italiano residente in Francia e iscritto all\u2019AIRE pu\u00f2 anche optare per il voto per i candidati ai seggi spettanti alla Francia; in tal caso voter\u00e0 presso i seggi istituiti dalle autorit\u00e0 francesi.<\/p>\n<p>Il doppio voto \u00e8 vietato: se si vota a favore di un candidato per i seggi spettanti all\u2019Italia non si potr\u00e0 esprimere il voto anche per un candidato per i seggi spettanti alla Francia e viceversa. Tale divieto si applica anche se l\u2019elettore \u00e8 in possesso di pi\u00f9 cittadinanze di Paesi membri dell\u2019Unione Europea: potr\u00e0 esercitare il diritto di voto per i rappresentanti spettanti a uno solo degli Stati di cui \u00e8 cittadino.<\/p>\n<p>Il doppio voto \u00e8 penalmente sanzionato anche nel senso che chi vota per i rappresentanti spettanti all\u2019Italia presso le sezioni elettorali istituite in Francia dagli uffici consolari NON potr\u00e0 farlo anche presso le sezioni elettorali in Italia, e viceversa.<\/p>\n<p>I cittadini italiani che sono permanentemente residenti in Francia e iscritti all\u2019AIRE e che non hanno optato per il voto a favore dei rappresentanti spettanti alla Francia saranno ammessi al voto per i candidati per i seggi spettanti all\u2019Italia senza necessit\u00e0 di presentare alcuna dichiarazione.<\/p>\n<p><strong>Principali norme di riferimento:<\/strong><\/p>\n<ul>\n<li>Legge 24 gennaio 1979, n. 18 \u2013 Elezione dei membri del Parlamento europeo spettanti all\u2019Italia.<\/li>\n<li>Decreto Legge 24 giugno 1994, n. 408, convertito con modificazioni in Legge 3 agosto 1994, n. 483 \u2013 Disposizioni urgenti in materia di elezioni al Parlamento europeo.<\/li>\n<li>Legge 27 aprile 2004, n. 78 \u2013 Disposizioni concernenti i membri del Parlamento europeo eletti in Italia, in attuazione della decisione 2002\/772\/CE del Consiglio.<\/li>\n<li>Legge 8 aprile 2004, n. 90 \u2013 Norme in materia di elezioni dei membri del Parlamento europeo e altre disposizioni inerenti ad elezioni da svolgersi nell\u2019anno 2004.<\/li>\n<li>Decreto-legge 27 gennaio 2009, n. 3 \u2013 Disposizioni urgenti per lo svolgimento nell\u2019anno 2009 delle consultazioni elettorali e referendarie<\/li>\n<li>Decreto legislativo 13 febbraio 2014, n. 11 \u2013 Attuazione della direttiva 2013\/1\/UE recante modifica della direttiva 93\/109\/CE relativamente a talune modalit\u00e0 di esercizio del diritto di eleggibilit\u00e0 alle elezioni del Parlamento europeo per i cittadini dell\u2019Unione che risiedono in uno Stato membro di cui non sono cittadini<\/li>\n<li>Legge 22 aprile 2014, n. 65 \u2013 Modifiche alla legge 24 gennaio 1979, n. 18, recante norme per l\u2019elezione dei membri del Parlamento europeo spettanti all\u2019Italia, in materia di garanzie per la rappresentanza di genere, e relative disposizioni transitorie inerenti alle elezioni da svolgere nell\u2019anno 2014<\/li>\n<\/ul>\n<p>Per la consultazione della normativa italiana vigente si suggerisce di visitare il sito\u00a0<a href=\"http:\/\/www.normattiva.it\/\">www.normattiva.it<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"Ai sensi del Decreto-legge 24 giugno 1994, n. 408, possono votare presso i seggi istituti dagli uffici consolari italiani in Francia per l\u2019elezione dei rappresentanti al Parlamento europeo spettanti all\u2019Italia: \u2013 i cittadini italiani residenti in Francia e iscritti all\u2019AIRE; \u2013 i cittadini italiani e i familiari con essi conviventi che si trovano temporaneamente in [&hellip;]","protected":false},"author":6,"featured_media":0,"parent":116,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2355","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=2355"}],"version-history":[{"count":3,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2355\/revisions"}],"predecessor-version":[{"id":2557,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/pages\/2355\/revisions\/2557"}],"up":[{"embeddable":true,"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/pages\/116"}],"wp:attachment":[{"href":"https:\/\/ambparigi.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=2355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}